{"id":232,"date":"2020-06-06T15:04:41","date_gmt":"2020-06-06T13:04:41","guid":{"rendered":"https:\/\/bannmuehle.wholewildworld.de\/?page_id=232"},"modified":"2020-11-25T11:24:18","modified_gmt":"2020-11-25T10:24:18","slug":"oeko-strom","status":"publish","type":"page","link":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/oeko-strom\/","title":{"rendered":"\u00d6ko-Strom"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"232\" class=\"elementor elementor-232\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baaeb1d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"baaeb1d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1ebd56\" data-id=\"e1ebd56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42aba73 elementor-widget elementor-widget-counter\" data-id=\"42aba73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Strom erzeugt die Bannm\u00fchle j\u00e4hrlich<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"350000\" data-from-value=\"500\" data-delimiter=\".\">500<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> kWh<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267bb48 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"267bb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Energie wird zum Einen aus den Wasserturbinen der Bannm\u00fchle gewonnen und zum Anderen aus einer Fotovoltaik-Anlage.<br \/>Zwischen 1911 und 1914 wurden anstelle des Wasserrades zwei Turbinen eingebaut, die seit Ende des ersten Weltkrieges zur Stromerzeugung genutzt werden. 1994 wurde eine General\u00fcberholung dieser Turbinen durchgef\u00fchrt.<\/p><p><a href=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-375\" src=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-1024x699.jpg\" alt=\"\" width=\"525\" height=\"358\" srcset=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-1024x699.jpg 1024w, https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-250x171.jpg 250w, https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-350x239.jpg 350w, https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-300x205.jpg 300w, https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-768x525.jpg 768w, https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2-1536x1049.jpg 1536w, https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/turbine-1-2.jpg 1842w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><\/p><p>Zwei stehende Francis-Schachtturbinen sorgen seitdem mit 25 KW bzw. 50 KW Leistung f\u00fcr die Stromversorgung der Bannm\u00fchle, wobei 90% der Leistung nicht am Hof verbraucht und deshalb an die Pfalzwerke weitergegeben werden. Eine gro\u00dfe Fotovoltaik-Anlage speist zus\u00e4tzlich Strom in das Hausnetz der Bannm\u00fchle ein.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-317941c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"317941c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/DSC07669-1024x576.jpg\" alt=\"Die zwei Generatoren\" \/><figcaption class=\"elementor-image-carousel-caption\">Die zwei Generatoren<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/DJI_0499-1024x576.jpg\" alt=\"DJI_0499\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/DSC07680-1024x576.jpg\" alt=\"Amperemeter und Voltmeter\" \/><figcaption class=\"elementor-image-carousel-caption\">Amperemeter und Voltmeter<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/DSC07706-1024x576.jpg\" alt=\"DSC07706\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bannmuehle.wholewildworld.de\/wp-content\/uploads\/2020\/06\/Turbinenplan_sw-1024x702.jpg\" alt=\"Turbinenplan_sw\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>500 kWh Strom erzeugt die Bannm\u00fchle j\u00e4hrlich Energie wird zum Einen aus den Wasserturbinen der Bannm\u00fchle gewonnen und zum Anderen aus einer Fotovoltaik-Anlage.Zwischen 1911 und 1914 wurden anstelle des Wasserrades zwei Turbinen eingebaut, die seit Ende des ersten Weltkrieges zur Stromerzeugung genutzt werden. 1994 wurde eine General\u00fcberholung dieser Turbinen durchgef\u00fchrt. Zwei stehende Francis-Schachtturbinen sorgen seitdem &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/bannmuehle.wholewildworld.de\/index.php\/oeko-strom\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e\u00d6ko-Strom\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-232","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/pages\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":17,"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/pages\/232\/revisions"}],"predecessor-version":[{"id":732,"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/pages\/232\/revisions\/732"}],"wp:attachment":[{"href":"https:\/\/bannmuehle.wholewildworld.de\/index.php\/wp-json\/wp\/v2\/media?parent=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}